{"id":3376,"date":"2022-06-07T10:55:23","date_gmt":"2022-06-07T08:55:23","guid":{"rendered":"https:\/\/villadutempsretrouve.com\/?post_type=oeuvres&#038;p=3376"},"modified":"2022-06-07T10:55:23","modified_gmt":"2022-06-07T08:55:23","slug":"assiette-parlante-bains-de-mer-iii-hippolyte-boulenger","status":"publish","type":"oeuvres","link":"https:\/\/villadutempsretrouve.com\/en\/oeuvres\/assiette-parlante-bains-de-mer-iii-hippolyte-boulenger\/","title":{"rendered":"Assiette parlante &#8220;Bains de mer III&#8221; \u2022 Hippolyte Boulenger"},"content":{"rendered":"","protected":false},"featured_media":0,"template":"","class_list":["post-3376","oeuvres","type-oeuvres","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Assiette parlante &quot;Bains de mer III&quot; \u2022 Hippolyte Boulenger - La Villa du temps retrouv\u00e9<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/villadutempsretrouve.com\/en\/oeuvres\/assiette-parlante-bains-de-mer-iii-hippolyte-boulenger\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Assiette parlante &quot;Bains de mer III&quot; \u2022 Hippolyte Boulenger - La Villa du temps retrouv\u00e9\" \/>\n<meta property=\"og:url\" content=\"https:\/\/villadutempsretrouve.com\/en\/oeuvres\/assiette-parlante-bains-de-mer-iii-hippolyte-boulenger\/\" \/>\n<meta property=\"og:site_name\" content=\"La Villa du temps retrouv\u00e9\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/villadutempsretrouve.com\\\/en\\\/oeuvres\\\/assiette-parlante-bains-de-mer-iii-hippolyte-boulenger\\\/\",\"url\":\"https:\\\/\\\/villadutempsretrouve.com\\\/en\\\/oeuvres\\\/assiette-parlante-bains-de-mer-iii-hippolyte-boulenger\\\/\",\"name\":\"Assiette parlante \\\"Bains de mer III\\\" \u2022 Hippolyte Boulenger - La Villa du temps retrouv\u00e9\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/villadutempsretrouve.com\\\/#website\"},\"datePublished\":\"2022-06-07T08:55:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/villadutempsretrouve.com\\\/en\\\/oeuvres\\\/assiette-parlante-bains-de-mer-iii-hippolyte-boulenger\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/villadutempsretrouve.com\\\/en\\\/oeuvres\\\/assiette-parlante-bains-de-mer-iii-hippolyte-boulenger\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/villadutempsretrouve.com\\\/en\\\/oeuvres\\\/assiette-parlante-bains-de-mer-iii-hippolyte-boulenger\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/villadutempsretrouve.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Assiette parlante &#8220;Bains de mer III&#8221; \u2022 Hippolyte Boulenger\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/villadutempsretrouve.com\\\/#website\",\"url\":\"https:\\\/\\\/villadutempsretrouve.com\\\/\",\"name\":\"La Villa du temps retrouv\u00e9\",\"description\":\"Mus\u00e9e consacr\u00e9 aux cultures de la Belle Epoque \u00e0 Cabourg\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/villadutempsretrouve.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Assiette parlante \"Bains de mer III\" \u2022 Hippolyte Boulenger - La Villa du temps retrouv\u00e9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/villadutempsretrouve.com\/en\/oeuvres\/assiette-parlante-bains-de-mer-iii-hippolyte-boulenger\/","og_locale":"en_US","og_type":"article","og_title":"Assiette parlante \"Bains de mer III\" \u2022 Hippolyte Boulenger - La Villa du temps retrouv\u00e9","og_url":"https:\/\/villadutempsretrouve.com\/en\/oeuvres\/assiette-parlante-bains-de-mer-iii-hippolyte-boulenger\/","og_site_name":"La Villa du temps retrouv\u00e9","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/villadutempsretrouve.com\/en\/oeuvres\/assiette-parlante-bains-de-mer-iii-hippolyte-boulenger\/","url":"https:\/\/villadutempsretrouve.com\/en\/oeuvres\/assiette-parlante-bains-de-mer-iii-hippolyte-boulenger\/","name":"Assiette parlante \"Bains de mer III\" \u2022 Hippolyte Boulenger - La Villa du temps retrouv\u00e9","isPartOf":{"@id":"https:\/\/villadutempsretrouve.com\/#website"},"datePublished":"2022-06-07T08:55:23+00:00","breadcrumb":{"@id":"https:\/\/villadutempsretrouve.com\/en\/oeuvres\/assiette-parlante-bains-de-mer-iii-hippolyte-boulenger\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/villadutempsretrouve.com\/en\/oeuvres\/assiette-parlante-bains-de-mer-iii-hippolyte-boulenger\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/villadutempsretrouve.com\/en\/oeuvres\/assiette-parlante-bains-de-mer-iii-hippolyte-boulenger\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/villadutempsretrouve.com\/en\/"},{"@type":"ListItem","position":2,"name":"Assiette parlante &#8220;Bains de mer III&#8221; \u2022 Hippolyte Boulenger"}]},{"@type":"WebSite","@id":"https:\/\/villadutempsretrouve.com\/#website","url":"https:\/\/villadutempsretrouve.com\/","name":"La Villa du temps retrouv\u00e9","description":"Mus\u00e9e consacr\u00e9 aux cultures de la Belle Epoque \u00e0 Cabourg","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/villadutempsretrouve.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/villadutempsretrouve.com\/en\/wp-json\/wp\/v2\/oeuvres\/3376","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/villadutempsretrouve.com\/en\/wp-json\/wp\/v2\/oeuvres"}],"about":[{"href":"https:\/\/villadutempsretrouve.com\/en\/wp-json\/wp\/v2\/types\/oeuvres"}],"wp:attachment":[{"href":"https:\/\/villadutempsretrouve.com\/en\/wp-json\/wp\/v2\/media?parent=3376"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}